	{"id":14274,"date":"2022-09-27T15:00:00","date_gmt":"2022-09-27T13:00:00","guid":{"rendered":"https:\/\/rebub.u-bordeaux.fr\/?p=14274"},"modified":"2022-09-28T12:10:14","modified_gmt":"2022-09-28T10:10:14","slug":"formations-de-rentree-gestion-des-ressources-deuxieme-round","status":"publish","type":"post","link":"https:\/\/rebub.u-bordeaux.fr\/index.php\/formations-de-rentree-gestion-des-ressources-deuxieme-round\/","title":{"rendered":"Formations de rentr\u00e9e : gestion des ressources, deuxi\u00e8me round !"},"content":{"rendered":"\n<p>Comme promis la semaine derni\u00e8re, nous vous en disons plus aujourd&rsquo;hui sur les deux autres modules pr\u00e9vus dans le nouveau cycle \u00ab\u00a0gestion des ressources\u00a0\u00bb. Contrairement aux deux premiers modules, ceux-ci ne sont pas r\u00e9serv\u00e9s aux d\u00e9butants.<\/p>\n\n\n\n<h4 id=\"stoc-un-troisieme-module-sur-la-vie-des-ressources-apres-le-catalogage\" class=\"wpig-heading\">Un troisi\u00e8me module sur la vie des ressources apr\u00e8s le catalogage<\/h4>\n\n\n\n<p>Ce troisi\u00e8me module aborde les diff\u00e9rentes op\u00e9rations n\u00e9cessaires pour g\u00e9rer les documents apr\u00e8s leur arriv\u00e9e dans nos collections. Ce module est destin\u00e9 \u00e0 un public plus large&nbsp;: au-del\u00e0 des charg\u00e9s de signalement, il s\u2019adresse \u00e0 toutes les personnes amen\u00e9es \u00e0 intervenir sur les collections dans le syst\u00e8me.<\/p>\n\n\n\n<p>Toutes les informations et le lien pour s\u2019inscrire sont dans le tableau suivant&nbsp;:<\/p>\n\n\n\n\n<table id=\"tablepress-143\" class=\"tablepress tablepress-id-143\">\n<thead>\n<tr class=\"row-1\">\n\t<th colspan=\"2\" class=\"column-1\"><strong>GESTION DES RESSOURCES  (MONOGRAPHIES) : LES AUTRES T\u00c2CHES AU QUOTIDIEN<\/strong><\/th><th class=\"column-3\"><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>Objectifs de la formation<\/strong><\/td><td colspan=\"2\" class=\"column-2\"><li>Savoir d\u00e9placer ou pilonner un exemplaire dans Alma<\/li><br \/>\n<li>Savoir modifier les informations de la holding ou de l\u2019exemplaire (recotation, etc)<\/li><br \/>\n<li>Savoir appliquer ou supprimer un traitement interne<\/li><br \/>\n<li>Savoir contr\u00f4ler la qualit\u00e9 du catalogage (niveau 1)<\/li><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><strong>Session(s)<\/strong><\/td><td class=\"column-2\">08\/10, 3h (horaires \u00e0 confirmer)<br \/>\n13\/10 de 9h \u00e0 12h<\/td><td class=\"column-3\">BU Sciences et Techniques, salle Dune<br \/>\n(arr\u00eat tram B Arts et M\u00e9tiers) [\u00e0 confirmer]<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><strong>Inscription<\/strong><\/td><td colspan=\"2\" class=\"column-2\"><a href=\"https:\/\/evento.renater.fr\/survey\/formation-scoop-la-gestion-des-ressources-dans-alma-les-autres-taches-au-quotidien-1qfjuqme\" target=\"_blank\" rel=\"noopener\">sur Evento<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-143 from cache -->\n\n\n\n<p>Et pour aller un peu plus loin, voici un r\u00e9sum\u00e9 de ce que les formateurs vous ont pr\u00e9par\u00e9&nbsp;:<\/p>\n\n\n\n<ul><li>La gestion des holdings<ul><li>Modifier la localisation et\/ou la cote<\/li><\/ul><ul><li>G\u00e9n\u00e9rer une cote automatique<\/li><\/ul><ul><li>Masquer une notice de la d\u00e9couverte<\/li><\/ul><\/li><li>La gestion des exemplaires<ul><li>Cote d\u2019exemplaire<\/li><\/ul><ul><li>Exceptions de circulation<\/li><\/ul><ul><li>Suppression d\u2019exemplaires<\/li><\/ul><ul><li>D\u00e9placements d\u2019exemplaires<\/li><\/ul><ul><li>Localisations temporaires<\/li><\/ul><ul><li>Traitements internes<\/li><\/ul><\/li><\/ul>\n\n\n\n<h4 id=\"stoc-un-quatrieme-module-pour-les-plus-aguerris\" class=\"wpig-heading\">Un quatri\u00e8me module, pour les plus aguerris<\/h4>\n\n\n\n<p>Ce module abordera la gestion avanc\u00e9e des ressources&nbsp;: parmi les sujets abord\u00e9s, on trouve la fusions des notices, cr\u00e9ation de jeux de r\u00e9sultats, traitements par lot, op\u00e9rations de contr\u00f4le qualit\u00e9\u2026<\/p>\n\n\n\n<p>Toutes les informations et le lien pour s\u2019inscrire sont dans le tableau suivant&nbsp;:<\/p>\n\n\n\n\n<table id=\"tablepress-144\" class=\"tablepress tablepress-id-144\">\n<thead>\n<tr class=\"row-1\">\n\t<th colspan=\"2\" class=\"column-1\"><strong>ATELIER GESTION DES RESSOURCES (MONOGRAPHIES) : GESTION DES RESSOURCES AVANCEE<\/strong><\/th><th class=\"column-3\"><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>Objectifs de l'atelier<\/strong><\/td><td colspan=\"2\" class=\"column-2\"><li>Savoir appliquer des traitements par lots<\/li><br \/>\n<li>Savoir contr\u00f4ler la qualit\u00e9 du catalogage<\/li><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><strong>Session(s)<\/strong><\/td><td class=\"column-2\">13\/10 de 14h \u00e0 17h<\/td><td class=\"column-3\">BU Sciences et Techniques, salle Dune<br \/>\n(arr\u00eat tram B Arts et M\u00e9tiers) [\u00e0 confirmer]<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><strong>Inscription<\/strong><\/td><td colspan=\"2\" class=\"column-2\"><a href=\"https:\/\/evento.renater.fr\/survey\/atelier-scoop-gestion-des-ressources-avancee-ekygpbjx\" target=\"_blank\" rel=\"noopener\">sur Evento<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-144 from cache -->\n\n\n\n<p>Vous l\u2019aurez compris, ce module s\u2019adresse aux personnes maitrisant parfaitement les points abord\u00e9s dans les sessions pr\u00e9c\u00e9dentes et qui souhaiteraient aller plus loin.&nbsp; Pour cette raison, nous souhaiterions tenter une approche de formation un peu diff\u00e9rente, et ajuster les contenus abord\u00e9s en fonction des besoins et\/ou des envies des personnes inscrites.<\/p>\n\n\n\n<p>Voici un r\u00e9sum\u00e9 de ce que les formateurs vous ont pr\u00e9par\u00e9&nbsp;:<\/p>\n\n\n\n<ul><li>La fusion de notices bibliographiques<\/li><li>Les traitements par lot :<ul><li>exporter les exemplaires physiques<\/li><\/ul><ul><li>mise \u00e0 jour exemplaires (exemples&nbsp; de champs sur lesquels intervenir : notes, codes statistiques, localisation temporaire, exception de circulation,&#8230;)<\/li><\/ul><\/li><li>V\u00e9rification et qualit\u00e9 de son propre catalogage<\/li><li>V\u00e9rification et qualit\u00e9 du catalogage en g\u00e9n\u00e9ral<ul><li>Avec les jeux de r\u00e9sultats Alma&nbsp;: astuces, bonnes pratiques, etc<\/li><\/ul><\/li><\/ul>\n\n\n\n<p>Pour nous indiquer les contenus que vous souhaitez aborder, merci de r\u00e9pondre \u00e0 la question incluse dans le formulaire d\u2019inscription.<\/p>\n\n\n\n<div class=\"message warning\"><p>L\u2019inscription \u00e0 une session ne vous dispense pas de suivre les proc\u00e9dures internes de validation de vos \u00e9tablissements.<\/p><\/div>\n\n\n\n<p>Pour tout renseignement compl\u00e9mentaire contacter&nbsp;: <a href=\"mailto:scoop@u-bordeaux.fr\" target=\"_blank\" rel=\"noreferrer noopener\">scoop@u-bordeaux.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Table des mati\u00e8res[ Show ]Un troisi\u00e8me module sur la vie des ressources apr\u00e8s le catalogageUn quatri\u00e8me module, pour les plus aguerrisComme promis la semaine derni\u00e8re, nous vous en disons plus aujourd&rsquo;hui sur les deux autres modules pr\u00e9vus dans le nouveau&#8230;<\/p>\n","protected":false},"author":78,"featured_media":1499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[58],"tags":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/14274"}],"collection":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/comments?post=14274"}],"version-history":[{"count":3,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/14274\/revisions"}],"predecessor-version":[{"id":14282,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/14274\/revisions\/14282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/media\/1499"}],"wp:attachment":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/media?parent=14274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/categories?post=14274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/tags?post=14274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}