	{"id":7438,"date":"2020-02-12T10:40:28","date_gmt":"2020-02-12T09:40:28","guid":{"rendered":"http:\/\/rebub.u-bordeaux.fr\/?p=7438"},"modified":"2020-02-12T11:12:56","modified_gmt":"2020-02-12T10:12:56","slug":"cest-arrive-pres-de-chez-vous-la-dame-de-la-page-356","status":"publish","type":"post","link":"https:\/\/rebub.u-bordeaux.fr\/index.php\/cest-arrive-pres-de-chez-vous-la-dame-de-la-page-356\/","title":{"rendered":"C\u2019est arriv\u00e9 pr\u00e8s de chez vous : la dame de la page 356"},"content":{"rendered":"<p>Rappelez-vous, \u00e0 deux reprises, nous partagions de riches d\u00e9couvertes faites au hasard de classement ou de rangement. Nous vous racontions <a href=\"http:\/\/rebub.u-bordeaux.fr\/index.php\/cest-arrive-pres-de-chez-vous-un-document-patrimonial-trouve-dans-un-placard\/\">l\u2019histoire de l\u2019atlas perdu au fond d\u2019un placard<\/a> (un comble pour une carte\u00a0!) et aussi l\u2019histoire du <a href=\"http:\/\/rebub.u-bordeaux.fr\/index.php\/cest-arrive-pres-de-chez-vous-patrimoine-en-carton\/\">registre des biblioth\u00e8ques de l\u2019Universit\u00e9 de Bordeaux<\/a>.<\/p>\n<p>Ce nouveau r\u00e9cit que nous vous proposons fait l\u2019objet maintenant d\u2019une recherche scientifique et a d\u00e9j\u00e0 b\u00e9n\u00e9fici\u00e9 d\u2019un article sur la revue BBF dans lequel vous trouverez le d\u00e9tail des investigations r\u00e9alis\u00e9es suite \u00e0 cette trouvaille : <a href=\"http:\/\/bbf.enssib.fr\/contributions\/un-portrait-inconnu-de-madame-lavoisier\">http:\/\/bbf.enssib.fr\/contributions\/un-portrait-inconnu-de-madame-lavoisier<\/a><\/p>\n<p>Alors asseyez-vous confortablement et laissez-nous vous raconter cette belle histoire.<\/p>\n<h3 id=\"stoc-le-point-de-depart\" class=\"wpig-heading\">Le point de d\u00e9part<\/h3>\n<p>Marie-Laure Saulnier est professeure agr\u00e9g\u00e9e de Sciences Physiques. En 2018, elle suit un master en \u00e9pist\u00e9mologie et histoire des sciences \u00e0 l\u2019universit\u00e9 Bordeaux Montaigne. Dans le cadre de son cursus, elle vient \u00e0 la biblioth\u00e8que universitaire des sciences et techniques (BUST) afin de suivre une UE intitul\u00e9e \u00ab\u00a0Sources de l\u2019Histoire des sciences\u00a0\u00bb organis\u00e9e par le service transversal des formations documentaires de l\u2019universit\u00e9 de Bordeaux. Lors d\u2019une de ces s\u00e9ances, elle d\u00e9couvre le fonds patrimonial de la BUST et visite la r\u00e9serve des documents anciens avec Claire-Lise Gauvain, du service du patrimoine documentaire.<\/p>\n<p>Un ensemble d\u2019ouvrages attire plus particuli\u00e8rement son attention, il s\u2019agit de petits formats dot\u00e9s majoritairement de belles reliures XVIII\u00e8me en cuir. Ils pr\u00e9sentent une particularit\u00e9 ch\u00e8re \u00e0 sa discipline de pr\u00e9dilection, la chimie, car ils ont appartenu \u00e0 Antoine Lavoisier. Appos\u00e9 sur le papier marbr\u00e9 \u00e0 coquilles recouvrant le contre-plat sup\u00e9rieur de leur reliure, l\u2019ex-libris grav\u00e9 du c\u00e9l\u00e8bre savant atteste de la pr\u00e9sence de ces ouvrages sur les \u00e9tag\u00e8res de sa biblioth\u00e8que il y a plus de deux si\u00e8cles. Grav\u00e9e par Pierre-Paul Delagardette, la vignette est parfois compl\u00e9t\u00e9e d\u2019une cote trac\u00e9e \u00e0 la plume avec cette m\u00eame encre bistre, qui sur certaines gardes blanches, laisse appara\u00eetre le nom du savant, tel une signature.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-7394 size-full\" src=\"http:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020310.jpg-1.jpg\" alt=\"\" width=\"600\" height=\"777\" srcset=\"https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020310.jpg-1.jpg 600w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020310.jpg-1-232x300.jpg 232w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Ces 73 documents font partie du fonds Alexandre Baudrimont, acquis par la biblioth\u00e8que en 1880 \u00e0 la mort de l\u2019ancien professeur de chimie de la facult\u00e9 des sciences de Bordeaux. Ils ont \u00e9t\u00e9 ajout\u00e9s \u00e0 l\u2019inventaire de la biblioth\u00e8que d\u2019Antoine Lavoisier (2600 titres) r\u00e9alis\u00e9 par Marco Beretta (Beretta, 1995) et figurent ainsi au <em>Panopticon Lavoisier<\/em> (Beretta et al., 1999) qui reconstitue le cabinet de travail du savant (archives num\u00e9ris\u00e9es, biblioth\u00e8que, instruments de laboratoire, collections de sp\u00e9cimens).<\/p>\n<p>La curiosit\u00e9 et la passion de notre visiteuse fait le reste. Il n\u2019en faut pas plus \u00e0 Marie-Laure Saulnier pour d\u00e9cider du sujet de son m\u00e9moire de master 1. Elle s\u2019int\u00e9ressera \u00e0 l\u2019histoire de ce fonds et pour cela, entreprendra la consultation syst\u00e9matique du fonds Baudrimont-Lavoisier \u00e0 la recherche des annotations de la main de leur ancien possesseur, Antoine Lavoisier.<\/p>\n<h3 id=\"stoc-pages-356-et-357\" class=\"wpig-heading\">Pages 356 et 357<\/h3>\n<p>Le 1<sup>er<\/sup> f\u00e9vrier est un nouveau jour de travail pour l\u2019\u00e9tudiante en master qui interroge une nouvelle fois les livres du fonds Baudrimont-Lavoisier. Jusqu\u2019\u00e0 pr\u00e9sent, la moisson est encourageante, plusieurs annotations de la main du chimiste ont \u00e9t\u00e9 trouv\u00e9es dans les ouvrages consult\u00e9s qui permettent d\u2019\u00e9tablir des liens entre ces ouvrages et ce que relate Lavoisier de ses lectures dans sa correspondance. Tout ceci permet de reconstituer par bribes l\u2019histoire de la biblioth\u00e8que du savant et l\u2019usage qu\u2019il en faisait. Elle ouvre alors le tome 3 des <em>Exp\u00e9riences physiques et chymiques, sur plusieurs mati\u00e8res relatives au commerce &amp; aux arts<\/em> du pharmacien et m\u00e9decin anglais William Lewis (1714\u20131781), traduit par Philippe-Florent de Puisieux et publi\u00e9 en 1769. L\u2019ancienne cote manuscrite de la biblioth\u00e8que Lavoisier y est inscrite : H n\u00b02. Elle commence \u00e0 le feuilleter.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-7393 size-full\" src=\"http:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090156.jpg\" alt=\"\" width=\"800\" height=\"617\" srcset=\"https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090156.jpg 800w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090156-300x231.jpg 300w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090156-768x592.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Les pages se tournent jusqu\u2019\u00e0 arriver aux pages 356 et 357. A cet instant les traits de Marie-Laure Saulnier se figent. Elle se trouve nez \u00e0 nez avec le portrait d\u00e9licat d\u2019une jeune femme grav\u00e9 sur une petite feuille de papier \u00e9cru, de la taille d\u2019une carte \u00e0 jouer, et cette femme semble la regarder.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-7395 size-full\" src=\"http:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020298.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020298.jpg 600w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1020298-225x300.jpg 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h3 id=\"stoc-un-tournant-dans-ses-recherches\" class=\"wpig-heading\">Un tournant dans ses recherches<\/h3>\n<p>Les recherches de notre \u00e9tudiante prennent alors une autre tournure. De nouvelles questions se posent \u00e0 elle\u00a0: depuis combien de temps ce portrait attend-t-il au milieu des pages de ce livre\u00a0? Qui se cache derri\u00e8re ces traits finement grav\u00e9s\u00a0? Pourquoi cette gravure a-t-elle \u00e9t\u00e9 gliss\u00e9e entre ces pages ?<\/p>\n<p>Marie-Laure Saulnier va, dans un premier temps, informer et solliciter les biblioth\u00e9caires. Pour cela elle va s\u2019adresser \u00e0 Mireille Bravo, charg\u00e9e depuis 2010 de signaler les fonds anciens de la BUST ainsi qu&rsquo;\u00e0 Claire-Lise Gauvain et Romain Wenz responsable du service du patrimoine documentaire.<\/p>\n<p>Le petit portrait g\u00e9n\u00e8re vite l\u2019enthousiasme mais, recherches faites, personne jusqu\u2019ici n\u2019avait mentionn\u00e9 sa pr\u00e9sence dans les fonds de la biblioth\u00e8que. L\u2019opuscule r\u00e9dig\u00e9 en 1995 \u00e0 propos du fonds Lavoisier par Ren\u00e9 Maury, conservateur alors en charge des fonds patrimoniaux de la BUST, mentionne bien l\u2019ouvrage de Lewis, mais non le portrait qu\u2019il abrite (Maury et al., 1995).<\/p>\n<h3 id=\"stoc-des-techniques-logicielles-a-la-rescousse\" class=\"wpig-heading\">Des techniques logicielles \u00e0 la rescousse<\/h3>\n<p>Pascal Duris, professeur d\u2019histoire des sciences, encourage son \u00e9tudiante \u00e0 approfondir ses recherches. La dame myst\u00e9rieuse intrigue tous ceux qui d\u00e9couvrent alors son existence \u2026\u00a0!<\/p>\n<p>La coiffure et les v\u00eatements de la dame \u00e9voquent une tenue de la fin du XVIII\u00e8me si\u00e8cle. Le petit portrait ayant \u00e9t\u00e9 retrouv\u00e9 dans un ouvrage de la biblioth\u00e8que du savant, Marie-Laure Saulnier d\u00e9cide d\u2019explorer tout d\u2019abord la piste des \u0153uvres artistiques et sources d\u2019inspiration en pr\u00e9sence au foyer du couple Lavoisier.<\/p>\n<p>C\u2019est vers Marie-Anne Paulze, \u00e9pouse Lavoisier, que ses recherches la conduisent rapidement. Madame Lavoisier est une collaboratrice pr\u00e9cieuse pour son mari qui traduit pour lui plusieurs ouvrages scientifiques de l\u2019anglais au fran\u00e7ais, l\u2019assiste dans son laboratoire et a acc\u00e8s \u00e0 sa biblioth\u00e8que. Elle pratique \u00e9galement le dessin et la gravure et s\u2019est perfectionn\u00e9e avec le peintre Jacques-Louis David qui a fait du couple Lavoisier un portrait en pied rest\u00e9 c\u00e9l\u00e8bre. Mais hormis un autoportrait peint lorsqu\u2019elle \u00e9tait toute jeune fille et des dessins et gravures d\u00e9taillant le laboratoire de son mari et ses instruments, peu d\u2019\u0153uvres de la main de Madame Lavoisier sont parvenues jusqu\u2019\u00e0 nous. C\u2019est donc chez le peintre David que Marie-Laure Saulnier recherche les mod\u00e8les f\u00e9minins susceptibles d\u2019avoir inspir\u00e9 l\u2019artiste ayant r\u00e9alis\u00e9 ce petit portrait. Quelques portraits f\u00e9minins peints par David sont retenus, ainsi que celui en pied du couple Lavoisier.<\/p>\n<p>Marie-Laure Saulnier a l\u2019id\u00e9e de les comparer \u00e0 l\u2019aide de logiciels de reconnaissance faciale. L\u2019\u00e9tude des cartographies des traits des visages f\u00e9minins collect\u00e9s rapproche le petit portrait inconnu de celui de madame Lavoisier et \u00e9carte les autres. L\u2019examen des croquis de laboratoire r\u00e9alis\u00e9s par madame Lavoisier o\u00f9 elle se figure elle-m\u00eame en train de prendre des notes corrobore cette premi\u00e8re piste bien que les techniques employ\u00e9es soient par ailleurs tr\u00e8s diff\u00e9rentes.<\/p>\n<p>S\u2019agit-il bien d\u2019un portrait de madame Lavoisier et a-t-il \u00e9t\u00e9 r\u00e9alis\u00e9 par madame Lavoisier elle-m\u00eame ? Tout reste \u00e0 pr\u00e9ciser puis \u00e9tayer. Il faut pour cela faire appel \u00e0 des experts sur le sujet.<\/p>\n<h3 id=\"stoc-le-voyage-de-la-dame\" class=\"wpig-heading\">Le voyage de la dame<\/h3>\n<p>Au mois de juillet, la dame sort de son exil en terre bordelaise et prend la direction de Paris, sous bonne escorte, accompagn\u00e9e de Marie-Laure Saulnier et de Claire-Lise Gauvain.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-7396 size-full\" src=\"http:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090161.jpg\" alt=\"\" width=\"800\" height=\"601\" srcset=\"https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090161.jpg 800w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090161-300x225.jpg 300w, https:\/\/rebub.u-bordeaux.fr\/wp-content\/uploads\/2020\/02\/P1090161-768x577.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>La premi\u00e8re \u00e9tape la m\u00e8ne \u00e0 l\u2019Institut de France et son Acad\u00e9mie des sciences o\u00f9 sont conserv\u00e9es les archives Lavoisier afin d\u2019y rencontrer Patrice Bret, secr\u00e9taire g\u00e9n\u00e9ral du Comit\u00e9 Lavoisier. Il conna\u00eet tr\u00e8s bien l\u2019histoire du chimiste et de sa femme.<\/p>\n<p>Lors de ce rendez-vous, le sp\u00e9cialiste remet en ordre les indices\u00a0: le livre dans lequel se trouvait le portrait appartenait bien au chimiste. Il y avait peu de femmes dans l\u2019entourage de la famille ce qui limite les mod\u00e8les pour un dessin. La physionomie du sujet de la gravure est proche de madame Lavoisier. Tous ces arguments laissent \u00e0 penser que la femme qui se trouve sur ce portait est bien Marie-Anne Pierrette Paulze Lavoisier.<\/p>\n<p>Par ailleurs, l\u2019\u00e9pouse du chimiste pratiquait la gravure puisqu\u2019elle a su r\u00e9aliser les croquis puis les gravures illustrant les planches de son <em>Trait\u00e9 \u00e9l\u00e9mentaire de chimie<\/em> (Lavoisier, 1793). Patrice Bret confirme la possibilit\u00e9 de l\u2019hypoth\u00e8se avanc\u00e9e par Marie-Laure Saulnier. Il peut s\u2019agir d\u2019un autoportrait r\u00e9alis\u00e9 par madame Lavoisier.<\/p>\n<p>Le second rendez-vous programm\u00e9 lors de ce voyage conduit la dame \u00e0 se pr\u00e9senter \u00e0 Xavier Seydoux, directeur de la galerie Seydoux et membre de la Chambre syndicale de l\u2019estampe, du dessin et du tableau.<\/p>\n<p>Lors de cet entretien, la dame se d\u00e9voile et l\u2019expert d\u00e9termine le type de papier utilis\u00e9, la m\u00e9thode employ\u00e9e et estime les dates de production probables. Il s\u2019agit d\u2019une gravure \u00a0d\u2019amateur r\u00e9alis\u00e9e sur un velin ou verg\u00e9 assez fort entre 1770 et 1830. <em>\u00ab\u00a0Le petit format utilis\u00e9 \u00e9tait d\u2019usage courant pour faire des essais en peu d\u2019exemplaires (10 \u00e0 20 au maximum), comme par exemple chez Jean-Pierre Norblin de la Gourdaine et ses \u00e9l\u00e8ves\u00a0\u00bb<\/em> explique l\u2019expert.<\/p>\n<p>Le voile se l\u00e8ve sur ce myst\u00e8re et cela commence \u00e0 \u00eatre plus clair. Les \u00e9l\u00e9ments recueillis lors de ces rencontres convergent vers la m\u00eame hypoth\u00e8se\u00a0: la dame est madame Lavoisier et ce portrait aurait \u00e9t\u00e9 r\u00e9alis\u00e9 de ses propres mains sans doute \u00e0 des fins d\u2019exercice.<\/p>\n<p>L\u2019illustre inconnue peut donc repartir \u00e0 la biblioth\u00e8que universitaire des sciences et techniques avec une identit\u00e9 retrouv\u00e9e.<\/p>\n<h3 id=\"stoc-au-coeur-de-toutes-les-attentions\" class=\"wpig-heading\">Au c\u0153ur de toutes les attentions<\/h3>\n<p>Mais l\u2019histoire ne s\u2019arr\u00eate pas l\u00e0 et la dame rest\u00e9e longtemps sous silence, continue de faire parler d\u2019elle. Le 13 f\u00e9vrier prochain, elle sera au centre de toutes les attentions lors d\u2019un colloque \u00e0 la Soci\u00e9t\u00e9 chimique de France \u00e0 Paris ayant pour th\u00e8me \u00ab\u00a0De Lavoisier \u00e0 Mendele\u00efev\u00a0\u00bb.<\/p>\n<p>Marie Laure Saulnier racontera son histoire, du moins celle que nous connaissons, celle d\u2019une petite gravure trouv\u00e9e au milieu d\u2019un ouvrage de physique-chimie. Elle fera s\u00fbrement s\u2019interroger les participants sur l\u2019usage des fonds anciens et de leur apport bien au-del\u00e0 de la recherche.<\/p>\n<p>Reste ces questions\u00a0: quelles mains gliss\u00e8rent ce portrait parmi ces pages, quelles pens\u00e9es animaient leur propri\u00e9taire lorsque qu\u2019il fut laiss\u00e9 l\u00e0\u00a0? A ces questions, ni le regard, ni la bouche de la dame qui y figure n\u2019y r\u00e9pondront sans doute jamais \u2026<\/p>\n<p>Jacques-Louis David a peint l\u2019illustre savant chimiste Lavoisier \u00e0 sa table de travail, la plume \u00e0 la main, comme inspir\u00e9 par sa muse, sa femme et collaboratrice se tenant debout \u00e0 ses c\u00f4t\u00e9s \u2026<\/p>\n<p>Toujours pr\u00e9sente, la \u00ab\u00a0dame\u00a0\u00bb des pages 356 et 357 a certainement conduit Marie-Laure Saulnier \u00e0 retrouver sa trace parmi les ouvrages de la biblioth\u00e8que de son mari.<\/p>\n<p>\u00a0<\/p>\n<p>\u00ab\u00a0<em>Paulze Lavoisier Sculpsit<\/em>\u00a0\u00bb \u2026\u00a0?<\/p>\n<p>\u00a0<\/p>\n<p>Fin de l\u2019histoire<\/p>\n<p>\u00a0<\/p>\n<p>Retrouvez la dame de la page 356 sur Babord-Num\u00a0: <a href=\"http:\/\/www.babordnum.fr\/items\/show\/1088\">http:\/\/www.babordnum.fr\/items\/show\/1088<\/a><\/p>\n<p>\u00a0<\/p>\n<p>Le m\u00e9moire de master 1 \u00e9crit par Marie-Laure Saulnier est consultable \u00e0 la BUST\u00a0:<\/p>\n<p>Saulnier Marie-Laure, <em>Constituer une biblioth\u00e8que au XVIII\u00e8me si\u00e8cle, exemple de la collection Lavoisier \u00e0 la BUST de Bordeaux<\/em>, [s.n.], [s.l.], 2017. Cote BUST\u202f: FR 697431.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Bibliographie\u00a0:<\/strong><\/p>\n<p>BERETTA, Marco, 1995. <em>Bibliotheca Lavoisieriana\u202f: the catalogue of the library of Antoine Laurent Lavoisier<\/em>. Firenze\u00a0: L. S. Olschki.<\/p>\n<p>BERETTA, Marco et alii, <em>Panopticon Lavoisier<\/em>. Disponible \u00e0 l\u2019adresse\u00a0: http:\/\/moro.imss.fi.it\/lavoisier\/index_fr.htm<\/p>\n<p>LAVOISIER, Antoine Laurent de et LAVOISIER, Marie-Anne, 1793. <em>Trait\u00e9 \u00e9l\u00e9mentaire de chimie, pr\u00e9sent\u00e9 dans un ordre nouveau et d\u2019apr\u00e8s les d\u00e9couvertes modernes<\/em>. A Paris\u202f: Chez Cuchet.<\/p>\n<p>MAURY, Ren\u00e9 et alii, 1995. <em>Lavoisier, ex-libris\u202f: une collection bordelaise<\/em>. Talence\u202f: SICOD-Biblioth\u00e8que universitaire des sciences et techniques de Bordeaux.<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p>Cr\u00e9dits images : Fabrice Zambau (Scoop \/ Universit\u00e9 de Bordeaux), Mireille Bravo (Direction de la documentation \/ Universit\u00e9 de Bordeaux)<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Table des mati\u00e8res[ Show ]Le point de d\u00e9partPages 356 et 357Un tournant dans ses recherchesDes techniques logicielles \u00e0 la rescousseLe voyage de la dameAu c\u0153ur de toutes les attentionsRappelez-vous, \u00e0 deux reprises, nous partagions de riches d\u00e9couvertes faites au hasard&#8230;<\/p>\n","protected":false},"author":46,"featured_media":7398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[47],"tags":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/7438"}],"collection":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7438"}],"version-history":[{"count":4,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/7438\/revisions"}],"predecessor-version":[{"id":7445,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/posts\/7438\/revisions\/7445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/media\/7398"}],"wp:attachment":[{"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rebub.u-bordeaux.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}